{"id":633,"count":3,"description":"Johann Finatzer \u00e8 nato a Bolzano nel 1973. Diploma in trombone presso il Conservatorio di Musica di Bolzano, perfezionamento con insegnanti di fama internazionale. Sostituto e solista dell'Orchestra Haydn di Bolzano e Trento dal 1995. Dal 1993 dirige le bande Kurtinig, Margreid, Truden, Terlan, Auer, St. Pauls. Attualmente dirige la Brassband \u00dcberetsch, la Brass Band Giovanile dell'Alto Adige e la Stadtkapelle Bozen (Banda Cittadina di Bolzano). Membro di varie formazioni di musica da camera come l'Ensemble Windkraft, il quartetto di tromboni Sonoro e il quintetto di ottoni Cinquino. Direttore artistico dell'associazione concertistica Forum Musik Kaltern e della Weinkl\u00e4nge-S\u00fcdtiroler Weinstra\u00dfe. Insegnante di trombone\/eufonio presso le scuole di musica di Appiano e Lana dal 1993. Formazione di insegnante di musica presso l'Universit\u00e0 di Bolzano\/Bressanone, con laurea nel 2009. Formazione di mentore, con laurea nel 2024. Compositore e giurato in concorsi.","link":"https:\/\/www.munodi-edition.com\/it\/composer\/finatzer-johann-it\/","name":"Finatzer Johann","slug":"finatzer-johann-it","taxonomy":"composer","parent":0,"meta":{"order":0},"acf":[],"_links":{"self":[{"href":"https:\/\/www.munodi-edition.com\/it\/wp-json\/wp\/v2\/composer\/633"}],"collection":[{"href":"https:\/\/www.munodi-edition.com\/it\/wp-json\/wp\/v2\/composer"}],"about":[{"href":"https:\/\/www.munodi-edition.com\/it\/wp-json\/wp\/v2\/taxonomies\/composer"}],"wp:post_type":[{"href":"https:\/\/www.munodi-edition.com\/it\/wp-json\/wp\/v2\/product?composer=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}